{"id":7753,"date":"2024-06-19T09:23:12","date_gmt":"2024-06-19T09:23:12","guid":{"rendered":"https:\/\/www.npf.ie\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/"},"modified":"2024-09-13T13:26:16","modified_gmt":"2024-09-13T13:26:16","slug":"glac-pairt-sa-chomhra","status":"publish","type":"page","link":"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/","title":{"rendered":"Glac P\u00e1irt sa Chomhr\u00e1"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-4d350eec alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-call-to-action uagb-block-65743264 wp-block-button\"><div class=\"uagb-cta__wrap\"><h2 class=\"uagb-cta__title\">Conas do thuairim\u00ed a chur in i\u00fal<\/h2><p class=\"uagb-cta__desc\">Is f\u00e9idir aighneachta\u00ed n\u00f3 tuairim\u00ed maidir leis an dr\u00e9acht-athbhreithni\u00fa ar an CNP agus ar Thuarasc\u00e1il Chomhshaoil agus ar an Achoimre Neamhtheicni\u00fail agus ar an Meas\u00fan\u00fa Strait\u00e9iseach Riosca i gC\u00e1s Tuilte de chuid MST a dh\u00e9anamh ar an <a href=\"https:\/\/consult.housing.gov.ie\/en\/browse\" target=\"_blank\" rel=\"noreferrer noopener\">tairseach comhairli\u00fach\u00e1in thiomnaithe<\/a>.<\/p><\/div><div class=\"uagb-cta__buttons\"><a href=\"https:\/\/consult.housing.gov.ie\/ga\/browse\" class=\"uagb-cta__button-link-wrapper wp-block-button__link\" target=\"_blank\" rel=\"noopener noreferrer\">Tairseach Comhairli\u00fach\u00e1in Thiomnaithe<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M504.3 273.6l-112.1 104c-6.992 6.484-17.18 8.218-25.94 4.406c-8.758-3.812-14.42-12.45-14.42-21.1L351.9 288H32C14.33 288 .0002 273.7 .0002 255.1S14.33 224 32 224h319.9l0-72c0-9.547 5.66-18.19 14.42-22c8.754-3.809 18.95-2.075 25.94 4.41l112.1 104C514.6 247.9 514.6 264.1 504.3 273.6z\"><\/path><\/svg><\/a><\/div><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6360dea7 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-1dbba383\">\n<p class=\"wp-block-paragraph\"><strong>De rogha air sin, <\/strong>is f\u00e9idir aighneachta\u00ed a dh\u00e9anamh sa phost chuig an seoladh seo a leanas: An Ch\u00e9ad Athbhreithni\u00fa ar Chomhairli\u00fach\u00e1n an Chreata N\u00e1isi\u00fanta Plean\u00e1la, An Roinn Tith\u00edochta, Rialtais \u00c1iti\u00fail agus Oidhreachta, Teach an Chustaim, Baile \u00c1tha Cliath 1, D01 W6X0.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fb49ab4b ticss-b9b29eca\"><h2 class=\"uagb-heading-text\"><strong>Comhairli\u00fach\u00e1n Poibl\u00ed maidir le Meas\u00fan\u00fa Timpeallachta<\/strong><\/h2><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">I gcomhr\u00e9ir le Treoir an Aontais Eorpaigh um Meas\u00fan\u00fa Strait\u00e9iseach Timpeallachta (MST) (2001\/42\/CE) agus Rialach\u00e1in na gComhphobal Eorpach (Meas\u00fan\u00fa Timpeallachta ar Phleananna agus Cl\u00e1ir \u00c1irithe) 2004, I.R. Uimh. 435 de 2004 (arna leas\u00fa le I.R. 200 de 2011), t\u00e1 Tuarasc\u00e1il Chomhshaoil agus Achoimre Neamhtheicni\u00fail MST ag gabh\u00e1il leis an Dr\u00e9acht Athbhreithnithe ar an CNP, agus t\u00e1 comhairli\u00fach\u00e1n poibl\u00ed \u00e1 dh\u00e9anamh i gcomhr\u00e9ir le Rialach\u00e1n 13(1)(b) de na Rialach\u00e1in sin.<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-eaf57daf\"><h2 class=\"uagb-heading-text\"><strong>Comhairli\u00fach\u00e1n Poibl\u00ed maidir le h\u00c9in agus Gn\u00e1th\u00f3ga N\u00e1d\u00fartha<\/strong><\/h2><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">I gcomhr\u00e9ir le Treoir an Aontais Eorpaigh maidir le Gn\u00e1th\u00f3ga (92\/43\/CEE) agus an Treoir maidir le h\u00c9in (2009\/147\/CE), rinneadh Meas\u00fanacht Chu\u00ed faoi Rialach\u00e1n 42A de Rialach\u00e1in an Aontais Eorpaigh (\u00c9in agus Gn\u00e1th\u00f3ga N\u00e1d\u00fartha) 2021 (I.R. Uimh. 293 de 2021), agus t\u00e1 comhairli\u00fach\u00e1n poibl\u00ed \u00e1 dh\u00e9anamh i gcomhr\u00e9ir le Rialach\u00e1n 42(13) de na Rialach\u00e1in sin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ba cheart aighneachta\u00ed n\u00f3 tuairim\u00ed maidir leis an R\u00e1iteas Tionchair Natura agus doicim\u00e9id chomhairli\u00fach\u00e1in \u00e1bhartha eile a dh\u00e9anamh go d\u00edreach chuig Aonad um Meas\u00fan\u00fa \u00c9iceola\u00edoch (AME) na Seirbh\u00edse P\u00e1irceanna N\u00e1isi\u00fanta agus Fiadh\u00falra tr\u00ed r\u00edomhphost chuig <a href=\"mailto:EAU@npws.gov.ie\">EAU@npws.gov.ie<\/a> n\u00f3 tr\u00edd an bpost chuig:<\/p>\n\n\n\n<p class=\"has-ast-global-color-4-background-color has-background wp-block-paragraph\">An Ch\u00e9ad Athbhreithni\u00fa ar an gCreat N\u00e1isi\u00fanta Plean\u00e1la,<br\/>Meas\u00fanacht Tionchair Natura,<br\/>Seomra 2.23 An tAonad um Meas\u00fan\u00fa \u00c9iceola\u00edoch,<br\/>An tSeirbh\u00eds P\u00e1irceanna N\u00e1isi\u00fanta agus Fiadh\u00falra,<br\/>90 Sr\u00e1id an R\u00ed Thuaidh,<br\/>Margadh na Feirme,<br\/>Baile \u00c1tha Cliath 7,<br\/>D07 N7CV.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Breithneoidh an tAonad um Meas\u00fan\u00fa \u00c9iceola\u00edoch na haighneachta\u00ed sin, agus beidh siad mar bhonn eolais do chinneadh de bhun Airteagal 6(3) den Treoir maidir le Gn\u00e1th\u00f3ga.<\/p>\n\n\n\n<p class=\"ticss-b9b29eca has-text-color has-link-color wp-elements-b93066ee384466316f9484b5e3b92f32 wp-block-paragraph\" style=\"color:#216760\"><strong>SPRIOCDH\u00c1TA LE HAGHAIDH AIGHNEACHTA\u00cd<\/strong><\/p>\n\n\n\n<p class=\"ticss-b9b29eca has-text-color has-link-color wp-elements-00c44689961d3fa3cf7f54f79593c40d wp-block-paragraph\" style=\"color:#216760\"><strong>Glacfar le haighneachta\u00ed \u00f3 D\u00e9 C\u00e9adaoin an 10 I\u00fail 2024 go 5pm D\u00e9ardaoin, an 12 Me\u00e1n F\u00f3mhair 2024 (an d\u00e1 dh\u00e1ta sin san \u00e1ireamh).<\/strong><\/p>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-c0c88dcb alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-2e1a3656\">\n<div class=\"wp-block-uagb-info-box uagb-block-d494640c uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><a href=\"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M0 64C0 28.65 28.65 0 64 0H224V128C224 145.7 238.3 160 256 160H384V448C384 483.3 355.3 512 320 512H64C28.65 512 0 483.3 0 448V64zM256 128V0L384 128H256z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Breathnaigh ar an Dr\u00e9acht Athbhreithnithe den Chreat N\u00e1isi\u00fanta Plean\u00e1la<\/h2><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ba8d2179\">\n<div class=\"wp-block-uagb-info-box uagb-block-070bf7b4 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><a href=\"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/foghlaim-faoin-bproiseas-athbhreithnithe-go-dti-seo\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 576 512\"><path d=\"M0 64C0 28.65 28.65 0 64 0H224V128C224 145.7 238.3 160 256 160H384V299.6L289.3 394.3C281.1 402.5 275.3 412.8 272.5 424.1L257.4 484.2C255.1 493.6 255.7 503.2 258.8 512H64C28.65 512 0 483.3 0 448V64zM256 128V0L384 128H256zM564.1 250.1C579.8 265.7 579.8 291 564.1 306.7L534.7 336.1L463.8 265.1L493.2 235.7C508.8 220.1 534.1 220.1 549.8 235.7L564.1 250.1zM311.9 416.1L441.1 287.8L512.1 358.7L382.9 487.9C378.8 492 373.6 494.9 368 496.3L307.9 511.4C302.4 512.7 296.7 511.1 292.7 507.2C288.7 503.2 287.1 497.4 288.5 491.1L303.5 431.8C304.9 426.2 307.8 421.1 311.9 416.1V416.1z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Foghlaim faoin<br\/>bPr\u00f3iseas Athbhreithnithe<br\/>go dt\u00ed seo<\/h2><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f79fb96a\">\n<div class=\"wp-block-uagb-info-box uagb-block-d04af065 uagb-infobox__content-wrap  uagb-infobox_cta-type-all uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><a href=\"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/ceisteanna-coitianta\/\" class=\"uagb-infobox-link-wrap uagb-infbox__link-to-all\" target=\"_self\" aria-label=\"Infobox Link\" rel=\"noopener noreferrer\" onclick=\"return true;\"><\/a><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 384 512\"><path d=\"M282.5 64H320C355.3 64 384 92.65 384 128V448C384 483.3 355.3 512 320 512H64C28.65 512 0 483.3 0 448V128C0 92.65 28.65 64 64 64H101.5C114.6 26.71 150.2 0 192 0C233.8 0 269.4 26.71 282.5 64zM192 128C209.7 128 224 113.7 224 96C224 78.33 209.7 64 192 64C174.3 64 160 78.33 160 96C160 113.7 174.3 128 192 128zM105.4 230.5C100.9 243 107.5 256.7 119.1 261.2C132.5 265.6 146.2 259.1 150.6 246.6L151.1 245.3C152.2 242.1 155.2 240 158.6 240H216.9C225.2 240 232 246.8 232 255.1C232 260.6 229.1 265.6 224.4 268.3L180.1 293.7C172.6 298 168 305.9 168 314.5V328C168 341.3 178.7 352 192 352C205.1 352 215.8 341.5 215.1 328.4L248.3 309.9C267.9 298.7 280 277.8 280 255.1C280 220.3 251.7 192 216.9 192H158.6C134.9 192 113.8 206.9 105.8 229.3L105.4 230.5zM192 384C174.3 384 160 398.3 160 416C160 433.7 174.3 448 192 448C209.7 448 224 433.7 224 416C224 398.3 209.7 384 192 384z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Ceisteanna Coitianta<br\/><\/h2><\/div><div class=\"uagb-ifb-button-wrapper wp-block-button\"><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>De rogha air sin, is f\u00e9idir aighneachta\u00ed a dh\u00e9anamh sa phost chuig an seoladh seo a leanas: An Ch\u00e9ad Athbhreithni\u00fa [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":7389,"parent":7745,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-7753","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Glac P\u00e1irt sa Chomhr\u00e1 - The National Planning Framework<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/\" \/>\n<meta property=\"og:locale\" content=\"ga_IE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Glac P\u00e1irt sa Chomhr\u00e1 - The National Planning Framework\" \/>\n<meta property=\"og:description\" content=\"De rogha air sin, is f\u00e9idir aighneachta\u00ed a dh\u00e9anamh sa phost chuig an seoladh seo a leanas: An Ch\u00e9ad Athbhreithni\u00fa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/\" \/>\n<meta property=\"og:site_name\" content=\"The National Planning Framework\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-13T13:26:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cdn.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\\\/glac-pairt-sa-chomhra\\\/\",\"url\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\\\/glac-pairt-sa-chomhra\\\/\",\"name\":\"Glac P\u00e1irt sa Chomhr\u00e1 - The National Planning Framework\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\\\/glac-pairt-sa-chomhra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\\\/glac-pairt-sa-chomhra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.npf.ie\\\/wp-content\\\/uploads\\\/unseen-studio-s9CC2SKySJM-unsplash.jpg\",\"datePublished\":\"2024-06-19T09:23:12+00:00\",\"dateModified\":\"2024-09-13T13:26:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\\\/glac-pairt-sa-chomhra\\\/#breadcrumb\"},\"inLanguage\":\"ga-IE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.npf.ie\\\/ga\\\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\\\/glac-pairt-sa-chomhra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ga-IE\",\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\\\/glac-pairt-sa-chomhra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.npf.ie\\\/wp-content\\\/uploads\\\/unseen-studio-s9CC2SKySJM-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/www.npf.ie\\\/wp-content\\\/uploads\\\/unseen-studio-s9CC2SKySJM-unsplash.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\\\/glac-pairt-sa-chomhra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comhairli\u00fach\u00e1n poibl\u00ed ar an Dr\u00e9acht Athbhreithnithe den Chreat N\u00e1isi\u00fanta Plean\u00e1la\",\"item\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Glac P\u00e1irt sa Chomhr\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/#website\",\"url\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/\",\"name\":\"National Planning Framework\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ga-IE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/#organization\",\"name\":\"Department of Housing, Local Government and Heritage\",\"url\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ga-IE\",\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.npf.ie\\\/wp-content\\\/uploads\\\/npf_logo_feb18_horizontal-3-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.npf.ie\\\/wp-content\\\/uploads\\\/npf_logo_feb18_horizontal-3-1-1.png\",\"width\":255,\"height\":46,\"caption\":\"Department of Housing, Local Government and Heritage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.npf.ie\\\/ga\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Glac P\u00e1irt sa Chomhr\u00e1 - The National Planning Framework","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/","og_locale":"ga_IE","og_type":"article","og_title":"Glac P\u00e1irt sa Chomhr\u00e1 - The National Planning Framework","og_description":"De rogha air sin, is f\u00e9idir aighneachta\u00ed a dh\u00e9anamh sa phost chuig an seoladh seo a leanas: An Ch\u00e9ad Athbhreithni\u00fa [&hellip;]","og_url":"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/","og_site_name":"The National Planning Framework","article_modified_time":"2024-09-13T13:26:16+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/cdn.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/","url":"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/","name":"Glac P\u00e1irt sa Chomhr\u00e1 - The National Planning Framework","isPartOf":{"@id":"https:\/\/www.npf.ie\/ga\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/#primaryimage"},"image":{"@id":"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash.jpg","datePublished":"2024-06-19T09:23:12+00:00","dateModified":"2024-09-13T13:26:16+00:00","breadcrumb":{"@id":"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/#breadcrumb"},"inLanguage":"ga-IE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/"]}]},{"@type":"ImageObject","inLanguage":"ga-IE","@id":"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/#primaryimage","url":"https:\/\/www.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash.jpg","contentUrl":"https:\/\/www.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/glac-pairt-sa-chomhra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.npf.ie\/ga\/"},{"@type":"ListItem","position":2,"name":"Comhairli\u00fach\u00e1n poibl\u00ed ar an Dr\u00e9acht Athbhreithnithe den Chreat N\u00e1isi\u00fanta Plean\u00e1la","item":"https:\/\/www.npf.ie\/ga\/comhairliuchan-poibli-ar-an-dreacht-athbhreithnithe-den-chreat-naisiunta-pleanala\/"},{"@type":"ListItem","position":3,"name":"Glac P\u00e1irt sa Chomhr\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/www.npf.ie\/ga\/#website","url":"https:\/\/www.npf.ie\/ga\/","name":"National Planning Framework","description":"","publisher":{"@id":"https:\/\/www.npf.ie\/ga\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.npf.ie\/ga\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ga-IE"},{"@type":"Organization","@id":"https:\/\/www.npf.ie\/ga\/#organization","name":"Department of Housing, Local Government and Heritage","url":"https:\/\/www.npf.ie\/ga\/","logo":{"@type":"ImageObject","inLanguage":"ga-IE","@id":"https:\/\/www.npf.ie\/ga\/#\/schema\/logo\/image\/","url":"https:\/\/www.npf.ie\/wp-content\/uploads\/npf_logo_feb18_horizontal-3-1-1.png","contentUrl":"https:\/\/www.npf.ie\/wp-content\/uploads\/npf_logo_feb18_horizontal-3-1-1.png","width":255,"height":46,"caption":"Department of Housing, Local Government and Heritage"},"image":{"@id":"https:\/\/www.npf.ie\/ga\/#\/schema\/logo\/image\/"}}]}},"spectra_custom_meta":{"adv-header-id-meta":[""],"stick-header-meta":[""],"theme-transparent-header-meta":[""],"ast-site-content-layout":["default"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_wp_page_template":["default"],"_thumbnail_id":["7389"],"_last_translation_edit_mode":["translation-editor"],"_wpml_word_count":["{\"total\":403,\"to_translate\":{\"en\":403}}"],"_edit_lock":["1720716774:7"],"_uag_custom_page_level_css":[""],"astra-migrate-meta-layouts":["set"],"footnotes":[""],"_edit_last":["7"],"rs_page_bg_color":["#ffffff"],"cmplz_hide_cookiebanner":[""],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"amazonS3_cache":["a:28:{s:57:\"\/\/www.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164.jpg\";a:2:{s:2:\"id\";s:4:\"7394\";s:11:\"source_type\";s:13:\"media-library\";}s:57:\"\/\/cdn.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164.jpg\";a:2:{s:2:\"id\";s:4:\"7394\";s:11:\"source_type\";s:13:\"media-library\";}s:65:\"\/\/www.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164-150x150.jpg\";a:2:{s:2:\"id\";s:4:\"7394\";s:11:\"source_type\";s:13:\"media-library\";}s:65:\"\/\/cdn.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164-150x150.jpg\";a:2:{s:2:\"id\";s:4:\"7394\";s:11:\"source_type\";s:13:\"media-library\";}s:65:\"\/\/www.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164-300x200.jpg\";a:2:{s:2:\"id\";s:4:\"7394\";s:11:\"source_type\";s:13:\"media-library\";}s:65:\"\/\/cdn.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164-300x200.jpg\";a:2:{s:2:\"id\";s:4:\"7394\";s:11:\"source_type\";s:13:\"media-library\";}s:66:\"\/\/www.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164-1024x683.jpg\";a:2:{s:2:\"id\";s:4:\"7394\";s:11:\"source_type\";s:13:\"media-library\";}s:66:\"\/\/cdn.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164-1024x683.jpg\";a:2:{s:2:\"id\";s:4:\"7394\";s:11:\"source_type\";s:13:\"media-library\";}s:65:\"\/\/www.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164-350x100.jpg\";a:2:{s:2:\"id\";s:4:\"7394\";s:11:\"source_type\";s:13:\"media-library\";}s:65:\"\/\/cdn.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164-350x100.jpg\";a:2:{s:2:\"id\";s:4:\"7394\";s:11:\"source_type\";s:13:\"media-library\";}s:70:\"\/\/www.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash.jpg\";a:2:{s:2:\"id\";s:4:\"7392\";s:11:\"source_type\";s:13:\"media-library\";}s:70:\"\/\/cdn.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash.jpg\";a:2:{s:2:\"id\";s:4:\"7392\";s:11:\"source_type\";s:13:\"media-library\";}s:78:\"\/\/www.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash-150x150.jpg\";a:2:{s:2:\"id\";s:4:\"7392\";s:11:\"source_type\";s:13:\"media-library\";}s:78:\"\/\/cdn.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash-150x150.jpg\";a:2:{s:2:\"id\";s:4:\"7392\";s:11:\"source_type\";s:13:\"media-library\";}s:78:\"\/\/www.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash-300x200.jpg\";a:2:{s:2:\"id\";s:4:\"7392\";s:11:\"source_type\";s:13:\"media-library\";}s:78:\"\/\/cdn.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash-300x200.jpg\";a:2:{s:2:\"id\";s:4:\"7392\";s:11:\"source_type\";s:13:\"media-library\";}s:79:\"\/\/www.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash-1024x683.jpg\";a:2:{s:2:\"id\";s:4:\"7392\";s:11:\"source_type\";s:13:\"media-library\";}s:79:\"\/\/cdn.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash-1024x683.jpg\";a:2:{s:2:\"id\";s:4:\"7392\";s:11:\"source_type\";s:13:\"media-library\";}s:78:\"\/\/www.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash-350x100.jpg\";a:2:{s:2:\"id\";s:4:\"7392\";s:11:\"source_type\";s:13:\"media-library\";}s:78:\"\/\/cdn.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash-350x100.jpg\";a:2:{s:2:\"id\";s:4:\"7392\";s:11:\"source_type\";s:13:\"media-library\";}s:57:\"\/\/www.npf.ie\/wp-content\/uploads\/A919yecys_1y0wbu7_srk.png\";a:2:{s:2:\"id\";s:4:\"6798\";s:11:\"source_type\";s:13:\"media-library\";}s:57:\"\/\/cdn.npf.ie\/wp-content\/uploads\/A919yecys_1y0wbu7_srk.png\";a:2:{s:2:\"id\";s:4:\"6798\";s:11:\"source_type\";s:13:\"media-library\";}s:65:\"\/\/www.npf.ie\/wp-content\/uploads\/A919yecys_1y0wbu7_srk-150x150.png\";a:2:{s:2:\"id\";s:4:\"6798\";s:11:\"source_type\";s:13:\"media-library\";}s:65:\"\/\/cdn.npf.ie\/wp-content\/uploads\/A919yecys_1y0wbu7_srk-150x150.png\";a:2:{s:2:\"id\";s:4:\"6798\";s:11:\"source_type\";s:13:\"media-library\";}s:65:\"\/\/www.npf.ie\/wp-content\/uploads\/A919yecys_1y0wbu7_srk-300x129.png\";a:2:{s:2:\"id\";s:4:\"6798\";s:11:\"source_type\";s:13:\"media-library\";}s:65:\"\/\/cdn.npf.ie\/wp-content\/uploads\/A919yecys_1y0wbu7_srk-300x129.png\";a:2:{s:2:\"id\";s:4:\"6798\";s:11:\"source_type\";s:13:\"media-library\";}s:66:\"\/\/www.npf.ie\/wp-content\/uploads\/A919yecys_1y0wbu7_srk-1024x442.png\";a:2:{s:2:\"id\";s:4:\"6798\";s:11:\"source_type\";s:13:\"media-library\";}s:66:\"\/\/cdn.npf.ie\/wp-content\/uploads\/A919yecys_1y0wbu7_srk-1024x442.png\";a:2:{s:2:\"id\";s:4:\"6798\";s:11:\"source_type\";s:13:\"media-library\";}}"],"slide_template":["default"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:2;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:1;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:7;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:3;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:53636:\".wp-block-uagb-container.uagb-block-4d350eec .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4d350eec .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4d350eec .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4d350eec .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4d350eec .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4d350eec{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4d350eec > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-4d350eec{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-8);row-gap: 20px;column-gap: 20px;}.uagb-block-65743264.wp-block-uagb-call-to-action .uagb-cta__title{color: #216760;margin-bottom: 10px;}.uagb-block-65743264.wp-block-uagb-call-to-action .uagb-cta__desc{margin-bottom: 10px;}.uagb-block-65743264 .uagb-cta__align-button-after{margin-left: 10px;}.uagb-block-65743264 .uagb-cta__align-button-before{margin-right: 10px;}.uagb-block-65743264.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper > svg{margin-left: 10px;}.uagb-block-65743264.wp-block-uagb-call-to-action a.uagb-cta-second__button > svg{margin-left: 10px;font-size: 14px;width: 14px;height: 14px;line-height: 14px;}.uagb-block-65743264 .uagb-cta__content-wrap{text-align: left;}.uagb-block-65743264 .uagb-cta__wrap{width: 60%;text-align: left;}.uagb-block-65743264.wp-block-uagb-call-to-action{text-align: left;padding-top: 10px;padding-bottom: 10px;padding-left: 0px;padding-right: 0px;}.uagb-block-65743264 .uagb-cta__left-right-wrap .uagb-cta__content{margin-left: 0px;}.uagb-block-65743264 .uagb-cta__buttons{column-gap: 15px;}.uagb-block-65743264.wp-block-uagb-call-to-action {display: flex;justify-content: space-between;}.uagb-block-65743264 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__content{width: 60%;}.uagb-block-65743264 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 40%;}.uagb-block-65743264.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper {align-self: center;height: fit-content;margin-left: auto;}.uagb-block-65743264.wp-block-uagb-call-to-action  {flex-direction: row;align-items: center;}.uagb-block-65743264.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button{align-self: center;height: fit-content;}.uagb-block-65743264.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:hover{background-color: !important;}.uagb-block-65743264.wp-block-uagb-call-to-action.wp-block-button a.uagb-cta-second__button:focus{background-color: !important;}.uagb-block-65743264 .uagb-cta__button-wrapper a.uagb-cta-typeof-button{color: #333;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.uagb-block-65743264.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: #333;border-style: solid;}.uagb-block-65743264.wp-block-uagb-call-to-action a.uagb-cta-second__button{text-transform: normal;text-decoration: none;font-size: 14px;}.uagb-block-65743264 .uagb-cta__title{font-size: 24px;}.uagb-block-65743264 .uagb-cta__desc{font-weight: 600;}.wp-block-uagb-container.uagb-block-6360dea7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6360dea7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6360dea7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6360dea7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6360dea7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6360dea7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6360dea7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: wrap;row-gap: 40px;column-gap: 40px;}.wp-block-uagb-container.uagb-block-6360dea7{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 40px;column-gap: 40px;}.wp-block-uagb-container.uagb-block-1dbba383 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1dbba383 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1dbba383 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1dbba383 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1dbba383 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1dbba383{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1dbba383 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-1dbba383{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-fb49ab4b.wp-block-uagb-advanced-heading .uagb-heading-text{color: #216760;}.wp-block-uagb-advanced-heading.uagb-block-fb49ab4b.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 16px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-fb49ab4b.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-fb49ab4b.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fb49ab4b.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fb49ab4b.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fb49ab4b .uagb-heading-text{font-size: 1.4em;}.wp-block-uagb-advanced-heading.uagb-block-eaf57daf.wp-block-uagb-advanced-heading .uagb-heading-text{color: #216760;}.wp-block-uagb-advanced-heading.uagb-block-eaf57daf.wp-block-uagb-advanced-heading {padding-bottom: 16px;}.wp-block-uagb-advanced-heading.uagb-block-eaf57daf.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-eaf57daf.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-eaf57daf.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-eaf57daf.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-eaf57daf .uagb-heading-text{font-size: 1.4em;}.wp-block-uagb-container.uagb-block-c0c88dcb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c0c88dcb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c0c88dcb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c0c88dcb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c0c88dcb .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c0c88dcb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c0c88dcb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-c0c88dcb{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 50px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2e1a3656 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e1a3656 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e1a3656 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2e1a3656 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2e1a3656 .uagb-container__video-wrap video{opacity: 0.15;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e1a3656{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e1a3656 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2e1a3656{box-shadow: 0px 50px 50px -30px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 100% 51%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/www.npf.ie\/wp-content\/uploads\/A919yecys_1y0wbu7_srk.png);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2e1a3656::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: #c3edb4;opacity: 0.85;}.uagb-block-d494640c .uagb-ifb-icon{width: 60px;line-height: 60px;}.uagb-block-d494640c .uagb-ifb-icon > span{font-size: 60px;width: 60px;line-height: 60px;color: #333;}.uagb-block-d494640c .uagb-ifb-icon svg{fill: #333;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 60px;height: 60px;line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-d494640c .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-d494640c .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 60px;height: 60px;line-height: 60px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-d494640c .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 60px;line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-d494640c .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 60px;line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-d494640c .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-d494640c .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d494640c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-d494640c .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-d494640c .uagb-ifb-title{text-decoration: underline;font-weight: 900;font-size: 20px;margin-bottom: 10px;}.uagb-block-d494640c .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-d494640c .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d494640c .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d494640c .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d494640c .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d494640c .uagb-infobox__content-wrap{text-align: center;}.uagb-block-d494640c.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-d494640c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 30px;padding-right: 30px;padding-bottom: 30px;padding-left: 30px;}.uagb-block-d494640c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 30px;padding-right: 30px;padding-bottom: 30px;padding-left: 30px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d494640c .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d494640c.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d494640c.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-d494640c.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-d494640c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-ba8d2179 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ba8d2179 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ba8d2179 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ba8d2179 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ba8d2179 .uagb-container__video-wrap video{opacity: 0.15;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ba8d2179{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ba8d2179 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ba8d2179{box-shadow: 0px 50px 50px -30px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 53% 45%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/www.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash.jpg);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ba8d2179::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: #cdd1ff;opacity: 0.85;}.uagb-block-070bf7b4 .uagb-ifb-icon{width: 60px;line-height: 60px;}.uagb-block-070bf7b4 .uagb-ifb-icon > span{font-size: 60px;width: 60px;line-height: 60px;color: #333;}.uagb-block-070bf7b4 .uagb-ifb-icon svg{fill: #333;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 60px;height: 60px;line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-070bf7b4 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-070bf7b4 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 60px;height: 60px;line-height: 60px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-070bf7b4 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 60px;line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-070bf7b4 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 60px;line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-070bf7b4 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-070bf7b4 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-070bf7b4 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-070bf7b4 .uagb-ifb-title{text-decoration: underline;font-weight: 900;font-size: 20px;margin-bottom: 10px;}.uagb-block-070bf7b4 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-070bf7b4 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-070bf7b4 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-070bf7b4 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-070bf7b4 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-070bf7b4 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-070bf7b4.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-070bf7b4.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 30px;padding-right: 30px;padding-bottom: 30px;padding-left: 30px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 30px;padding-right: 30px;padding-bottom: 30px;padding-left: 30px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-070bf7b4 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-070bf7b4.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-070bf7b4.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-070bf7b4.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-f79fb96a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f79fb96a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f79fb96a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f79fb96a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f79fb96a .uagb-container__video-wrap video{opacity: 0.15;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f79fb96a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f79fb96a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f79fb96a{box-shadow: 0px 50px 50px -30px #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 96% 98%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/www.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164.jpg);background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f79fb96a::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: #ffcccc;opacity: 0.85;}.uagb-block-d04af065 .uagb-ifb-icon{width: 60px;line-height: 60px;}.uagb-block-d04af065 .uagb-ifb-icon > span{font-size: 60px;width: 60px;line-height: 60px;color: #333;}.uagb-block-d04af065 .uagb-ifb-icon svg{fill: #333;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 60px;height: 60px;line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-d04af065 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-d04af065 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 60px;height: 60px;line-height: 60px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-d04af065 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 60px;line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-d04af065 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 60px;line-height: 60px;font-size: 60px;color: #333;fill: #333;}.uagb-block-d04af065 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-d04af065 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d04af065.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-d04af065 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-d04af065 .uagb-ifb-title{text-decoration: underline;font-weight: 900;font-size: 20px;margin-bottom: 10px;}.uagb-block-d04af065 .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-d04af065 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d04af065 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d04af065 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d04af065 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d04af065 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-d04af065.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-d04af065.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 30px;padding-right: 30px;padding-bottom: 30px;padding-left: 30px;}.uagb-block-d04af065.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 30px;padding-right: 30px;padding-bottom: 30px;padding-left: 30px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d04af065 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d04af065.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d04af065.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-d04af065.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-d04af065.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4d350eec{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4d350eec > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4d350eec{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-8);}.uagb-block-65743264.wp-block-uagb-call-to-action.uagb-cta__content-stacked-tablet {display: inherit;}.uagb-block-65743264.uagb-cta__content-stacked-tablet .uagb-cta__wrap{width: 100%;}.uagb-block-65743264 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 40%;}.uagb-block-65743264 .uagb-cta__wrap{text-align: center;}.uagb-block-65743264.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}.uagb-block-65743264.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{border-style: solid;border-color: #333;}.uagb-block-65743264.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6360dea7{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6360dea7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6360dea7{padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1dbba383{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1dbba383 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1dbba383{padding-top: 10px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c0c88dcb{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c0c88dcb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-c0c88dcb{padding-top: 20px;padding-bottom: 50px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e1a3656{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e1a3656 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2e1a3656{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.npf.ie\/wp-content\/uploads\/A919yecys_1y0wbu7_srk.png);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-2e1a3656::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #c3edb4;opacity: 0.85;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 60px;height: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 60px;font-size: 60px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d494640c .uagb-ifb-icon{width: 60px;line-height: 60px;}.uagb-block-d494640c .uagb-ifb-icon > span{font-size: 60px;width: 60px;line-height: 60px;}.uagb-block-d494640c .uagb-iconbox-icon-wrap{width: 60px;height: 60px;line-height: 60px;}.uagb-block-d494640c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d494640c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d494640c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ba8d2179{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ba8d2179 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;}.wp-block-uagb-container.uagb-block-ba8d2179{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash.jpg);background-clip: padding-box;align-items: center;}.wp-block-uagb-container.uagb-block-ba8d2179::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #cdd1ff;opacity: 0.85;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 60px;height: 60px;line-height: 60px;font-size: 60px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 60px;font-size: 60px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-070bf7b4 .uagb-ifb-icon{width: 60px;line-height: 60px;}.uagb-block-070bf7b4 .uagb-ifb-icon > span{font-size: 60px;width: 60px;line-height: 60px;}.uagb-block-070bf7b4 .uagb-iconbox-icon-wrap{width: 60px;height: 60px;line-height: 60px;}.uagb-block-070bf7b4 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-070bf7b4 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f79fb96a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f79fb96a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;}.wp-block-uagb-container.uagb-block-f79fb96a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164.jpg);background-clip: padding-box;align-items: center;}.wp-block-uagb-container.uagb-block-f79fb96a::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #ffcccc;opacity: 0.85;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 60px;height: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 60px;font-size: 60px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d04af065 .uagb-ifb-icon{width: 60px;line-height: 60px;}.uagb-block-d04af065 .uagb-ifb-icon > span{font-size: 60px;width: 60px;line-height: 60px;}.uagb-block-d04af065 .uagb-iconbox-icon-wrap{width: 60px;height: 60px;line-height: 60px;}.uagb-block-d04af065 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d04af065 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d04af065.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4d350eec{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4d350eec > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4d350eec{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 30px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-8);}.uagb-block-65743264.wp-block-uagb-call-to-action.uagb-cta__content-stacked-mobile {display: inherit;}.uagb-block-65743264.uagb-cta__content-stacked-mobile .uagb-cta__wrap{width: 100%;}.uagb-block-65743264 .uagb-cta__buttons{justify-content: center;}.uagb-block-65743264 .uagb-cta__content-right .uagb-cta__left-right-wrap .uagb-cta__link-wrapper{width: 40%;}.uagb-block-65743264 .uagb-cta__wrap{text-align: center;}.uagb-block-65743264.wp-block-uagb-call-to-action {flex-direction: column;align-items: center;}.uagb-block-65743264.wp-block-uagb-call-to-action a.uagb-cta__button-link-wrapper{border-style: solid;border-color: #333;}.uagb-block-65743264.wp-block-uagb-call-to-action.wp-block-button .uagb-cta__buttons a.uagb-cta__button-link-wrapper.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6360dea7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6360dea7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6360dea7{padding-top: 0px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1dbba383{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1dbba383 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1dbba383{padding-top: 10px;padding-bottom: 0px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c0c88dcb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c0c88dcb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c0c88dcb{padding-top: 20px;padding-bottom: 50px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2e1a3656{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2e1a3656 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2e1a3656{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.npf.ie\/wp-content\/uploads\/A919yecys_1y0wbu7_srk.png);background-clip: padding-box;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2e1a3656::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #c3edb4;opacity: 0.85;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 60px;height: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 60px;font-size: 60px;}.uagb-block-d494640c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d494640c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d494640c .uagb-ifb-icon{width: 60px;line-height: 60px;}.uagb-block-d494640c .uagb-ifb-icon > span{font-size: 60px;width: 60px;line-height: 60px;}.uagb-block-d494640c .uagb-iconbox-icon-wrap{width: 60px;height: 60px;line-height: 60px;}.uagb-block-d494640c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d494640c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ba8d2179{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ba8d2179 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ba8d2179{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.npf.ie\/wp-content\/uploads\/kelly-sikkema-lFtttcsx5Vk-unsplash.jpg);background-clip: padding-box;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ba8d2179::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #cdd1ff;opacity: 0.85;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 60px;height: 60px;line-height: 60px;font-size: 60px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 60px;font-size: 60px;}.uagb-block-070bf7b4 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-070bf7b4 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-070bf7b4 .uagb-ifb-icon{width: 60px;line-height: 60px;}.uagb-block-070bf7b4 .uagb-ifb-icon > span{font-size: 60px;width: 60px;line-height: 60px;}.uagb-block-070bf7b4 .uagb-iconbox-icon-wrap{width: 60px;height: 60px;line-height: 60px;}.uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-070bf7b4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f79fb96a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f79fb96a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f79fb96a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.npf.ie\/wp-content\/uploads\/pexels-pixabay-221164.jpg);background-clip: padding-box;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-f79fb96a::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background: #ffcccc;opacity: 0.85;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 60px;height: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 60px;font-size: 60px;}.uagb-block-d04af065 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d04af065 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 60px;line-height: 60px;font-size: 60px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d04af065 .uagb-ifb-icon{width: 60px;line-height: 60px;}.uagb-block-d04af065 .uagb-ifb-icon > span{font-size: 60px;width: 60px;line-height: 60px;}.uagb-block-d04af065 .uagb-iconbox-icon-wrap{width: 60px;height: 60px;line-height: 60px;}.uagb-block-d04af065.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d04af065.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}}.wp-block-uagb-container.uagb-block-5aee6c9c.wp-block-uagb-container{color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-block-5aee6c9c.wp-block-uagb-container *{color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-block-5aee6c9c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5aee6c9c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5aee6c9c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5aee6c9c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5aee6c9c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5aee6c9c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5aee6c9c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5aee6c9c{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #30665f;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-5aee6c9c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5aee6c9c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5aee6c9c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #30665f;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-5aee6c9c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5aee6c9c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5aee6c9c{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #30665f;}}.wp-block-uagb-container.uagb-block-58e00206.wp-block-uagb-container{color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-block-58e00206.wp-block-uagb-container *{color: var(--ast-global-color-5);}.wp-block-uagb-container.uagb-block-58e00206 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-58e00206 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-58e00206 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-58e00206 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-58e00206 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-58e00206{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-58e00206 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-58e00206{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #30665f;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-58e00206{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-58e00206 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-58e00206{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #30665f;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-58e00206{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-58e00206 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-58e00206{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #30665f;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:7:{i:0;s:14:\"uagb\/container\";i:1;s:19:\"uagb\/call-to-action\";i:4;s:14:\"core\/paragraph\";i:5;s:21:\"uagb\/advanced-heading\";i:8;s:13:\"uagb\/info-box\";i:9;s:9:\"core\/list\";i:10;s:14:\"core\/list-item\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1784155231\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash.jpg",1920,1280,false],"thumbnail":["https:\/\/www.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash-150x150.jpg",150,150,true],"medium":["https:\/\/www.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash-300x200.jpg",300,200,true],"medium_large":["https:\/\/www.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash-768x512.jpg",768,512,true],"large":["https:\/\/www.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/www.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/www.npf.ie\/wp-content\/uploads\/unseen-studio-s9CC2SKySJM-unsplash.jpg",1920,1280,false]},"uagb_author_info":{"display_name":"Andrew Brennan","author_link":"https:\/\/www.npf.ie\/ga\/author\/andrew-brennan\/"},"uagb_comment_info":0,"uagb_excerpt":"De rogha air sin, is f\u00e9idir aighneachta\u00ed a dh\u00e9anamh sa phost chuig an seoladh seo a leanas: An Ch\u00e9ad Athbhreithni\u00fa [&hellip;]","_links":{"self":[{"href":"https:\/\/www.npf.ie\/ga\/wp-json\/wp\/v2\/pages\/7753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.npf.ie\/ga\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.npf.ie\/ga\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.npf.ie\/ga\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.npf.ie\/ga\/wp-json\/wp\/v2\/comments?post=7753"}],"version-history":[{"count":5,"href":"https:\/\/www.npf.ie\/ga\/wp-json\/wp\/v2\/pages\/7753\/revisions"}],"predecessor-version":[{"id":7905,"href":"https:\/\/www.npf.ie\/ga\/wp-json\/wp\/v2\/pages\/7753\/revisions\/7905"}],"up":[{"embeddable":true,"href":"https:\/\/www.npf.ie\/ga\/wp-json\/wp\/v2\/pages\/7745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.npf.ie\/ga\/wp-json\/wp\/v2\/media\/7389"}],"wp:attachment":[{"href":"https:\/\/www.npf.ie\/ga\/wp-json\/wp\/v2\/media?parent=7753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}